{"id":53670,"date":"2024-11-01T09:07:41","date_gmt":"2024-11-01T09:07:41","guid":{"rendered":"https:\/\/taggrs.io\/leadpages-server-side-tracking-landing-pages-serverseitig-einrichten\/"},"modified":"2025-08-26T12:27:24","modified_gmt":"2025-08-26T12:27:24","slug":"leadpages-server-side-tracking","status":"publish","type":"post","link":"https:\/\/taggrs.io\/de\/leadpages-server-side-tracking\/","title":{"rendered":"Leadpages Server Side Tracking - Landing Pages serverseitig einrichten"},"content":{"rendered":"\n<p>Sie m\u00f6chten serverseitige Benutzerdaten von Ihrer <a href=\"https:\/\/www.leadpages.com\/\" target=\"_blank\" rel=\"noopener\">Leadpages-Landing<\/a> Page messen. In diesem Blog f\u00fchren wir Sie Schritt f\u00fcr Schritt durch die Einrichtung des <a href=\"https:\/\/taggrs.io\/de\/server-side-tracking\/\">Server Side Tracking<\/a> f\u00fcr Leadpages.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Tracking Session #9 Leadpages Server Side Tracking\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/KZ3JgR5_VOs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"wat-is-leadpages\">Was ist Leadpages?<\/h2>\n\n\n\n<p>Leadpages ist ein beliebtes Tool f\u00fcr die Erstellung von Landing Pages und die Optimierung der Conversion. Es erm\u00f6glicht Benutzern die einfache Erstellung professioneller, responsiver Landing Pages, ohne dass technische Kenntnisse erforderlich sind. Mit Leadpages k\u00f6nnen Sie schnell und effizient Leads generieren, Abonnenten gewinnen und die Konversionsraten steigern. Der Drag-and-Drop-Builder, umfangreiche Integrationen und anpassbare Vorlagen machen es zu einer vielseitigen L\u00f6sung sowohl f\u00fcr kleine Unternehmen als auch f\u00fcr Gro\u00dfunternehmen.   <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"584\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/11\/leadpages-home-page-1024x584.png\" alt=\"leadpages-home-page\" class=\"wp-image-53651\" title=\"\"><\/figure>\n\n\n\n<h2 id=\"was-sind-die-vorteile-von-leadpages\" class=\"wp-block-heading\">Was sind die Vorteile von Leadpages?<\/h2>\n\n\n\n<p>Hier sind die 7 Vorteile von Leadpages:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Benutzerfreundlichkeit<\/strong>: Dank des Drag-and-Drop-Builders k\u00f6nnen Benutzer auch ohne technische Kenntnisse professionelle Landing Pages erstellen.<\/li>\n\n\n\n<li><strong>Responsive Designs<\/strong>: Landing Pages sehen sowohl auf dem Desktop als auch auf mobilen Ger\u00e4ten gut aus.<\/li>\n\n\n\n<li><strong>Schnelle Implementierung<\/strong>: Sie k\u00f6nnen voll funktionsf\u00e4hige Seiten in k\u00fcrzester Zeit einrichten.<\/li>\n\n\n\n<li><strong>Integrationen<\/strong>: Leadpages l\u00e4sst sich nahtlos in g\u00e4ngige Marketing-Tools wie CRM-Systeme, E-Mail-Marketing-Software und Werbeplattformen integrieren.<\/li>\n\n\n\n<li><strong>A\/B-Tests<\/strong>: Diese Funktion hilft bei der Optimierung von Landing Pages, indem verschiedene Versionen getestet und die besten ausgew\u00e4hlt werden.<\/li>\n\n\n\n<li><strong>Konversionsorientiert<\/strong>: Das Tool bietet Vorlagen und Funktionen, die darauf ausgerichtet sind, die Konversionsrate zu maximieren.<\/li>\n\n\n\n<li><strong>Analytik<\/strong>: Detaillierte Berichte und Analysen helfen, die Leistung zu messen und Marketingstrategien zu verfeinern.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"welke-events-kun-je-meten-in-Leadpages\">Welche Ereignisse k\u00f6nnen Sie in Leadpages messen?<\/h2>\n\n\n\n<p>Mehrere Ereignisse k\u00f6nnen \u00fcber Leadpages gemessen werden.  <\/p>\n\n\n\n<p>Hier sind 3 Beispiele:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Seitenansichten<\/li>\n\n\n\n<li>Anklicken von Schaltfl\u00e4chen<\/li>\n\n\n\n<li>Formular einreichen.  <\/li>\n<\/ul>\n\n\n\n<p>Leadpages bietet keine Datenebenen-Ereignisse beim Ausf\u00fcllen eines Formulars. Daher ist es am besten, mit einem zu arbeiten:   <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ausl\u00f6ser der Dankeseite<\/strong><\/li>\n\n\n\n<li><strong>Element Sichtbarkeit<\/strong><\/li>\n\n\n\n<li><strong>Klicken Sie auf<\/strong> <\/li>\n\n\n\n<li><strong>Schaltfl\u00e4che Senden<\/strong>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Leadpages-Server-Side-Tracking-instellen\">Leadpages Server Side Tracking einrichten<\/h2>\n\n\n\n<p>Hier erkl\u00e4ren wir Ihnen Schritt f\u00fcr Schritt, wie Sie das Server Side Tracking f\u00fcr Leadpages einrichten.<\/p>\n\n\n\n<h3 id=\"1-google-tag-manager-server-erstellen\" class=\"wp-block-heading\">1. Google Tag Manager Server erstellen<\/h3>\n\n\n\n<p><a href=\"https:\/\/dashboard.taggrs.io\/register\">Starten Sie TAGGRS kostenlos<\/a>, um Ihr kostenloses Konto zu er\u00f6ffnen. Erstellen Sie dann einen neuen sGTM-Container in demselben Konto wie Ihr Web-GTM-Container.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/new-sgtm-container-1024x741.png\" alt=\"create-new-sgtm-container\" class=\"wp-image-53417\" title=\"\"><\/figure>\n\n\n\n<p>Nennen Sie Ihren neuen Server GTM-Container. Es ist sinnvoll, Server daneben zu setzen, damit Sie sp\u00e4ter leicht zwischen Ihrem Web- und Server-Container unterscheiden k\u00f6nnen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/name-gtm-server-1024x741.png\" alt=\"name-gtm-server\" class=\"wp-image-53422\" title=\"\"><\/figure>\n\n\n\n<p>W\u00e4hlen Sie Server. Klicken Sie dann auf Erstellen, um den Container zu erstellen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/choose-server-create-1024x741.png\" alt=\"server-erstellen-w\u00e4hlen\" class=\"wp-image-53427\" title=\"\"><\/figure>\n\n\n\n<p>W\u00e4hlen Sie dann die <strong>manuelle Bereitstellung des Tagging-Servers<\/strong>. Das liegt daran, dass wir mit Servern arbeiten, die von TAGGRS und nicht von Google selbst gehostet werden, was die Einrichtung viel einfacher und billiger pro Monat macht. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/choose-manually-server-1024x741.png\" alt=\"manuell-server ausw\u00e4hlen\" class=\"wp-image-53433\" title=\"\"><\/figure>\n\n\n\n<p>Kopieren Sie den Code der Containerkonfiguration.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/copy-config-code-1024x741.png\" alt=\"copy-config-code\" class=\"wp-image-53438\" title=\"\"><\/figure>\n\n\n\n<p>F\u00fcgen Sie den GTM-Container-Konfigurationscode unter 'Container-Konfiguration' w\u00e4hrend der Einrichtung Ihres TAGGRS-Kontos ein. W\u00e4hlen Sie au\u00dferdem eine Subdomain, auf der Sie den sGTM-Container platzieren m\u00f6chten. Hier ist dies <a href=\"\">sst.demo1.taggrs.io<\/a>. Klicken Sie anschlie\u00dfend auf 'Speichern'.   <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/paste-container-config-1024x741.png\" alt=\"paste-container-config\" class=\"wp-image-53444\" title=\"\"><\/figure>\n\n\n\n<p>Klicken Sie auf Einstellungen und f\u00fcgen Sie diese DNS-Einstellungen zu Ihrer Domain hinzu.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/add-dns-domain-1024x741.png\" alt=\"add-dns-settings-to-your-domain\" class=\"wp-image-53449\" title=\"\"><\/figure>\n\n\n\n<p>Gehen Sie nun zur\u00fcck zu Ihrem Server-GTM-Container und klicken Sie auf Admin.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/back-click-admin-1024x741.png\" alt=\"zur\u00fcck-zu-ihrem-gtm-container-und-klick-admin\" class=\"wp-image-53454\" style=\"width:840px;height:auto\" title=\"\"><\/figure>\n\n\n\n<p>Gehen Sie zu den Container-Einstellungen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/go-container-settings-1024x741.png\" alt=\"go-container-to-settings\" class=\"wp-image-53459\" title=\"\"><\/figure>\n\n\n\n<p>F\u00fcgen Sie die gleiche Server-Container-URL wie bei der TAGGRS-Einrichtung hinzu.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/add-same-url-1024x741.png\" alt=\"add-same-server-container-url-\u00e4hnlich-mit-taggrs-setup.png\" class=\"wp-image-53464\" title=\"\"><\/figure>\n\n\n\n<p>Wir haben nun einen Container auf TAGGRS erstellt und den Server-Container erstellt<\/p>\n\n\n\n<h3 id=\"3-fuegen-sie-das-erweiterte-tracking-skript-zu-den-leadpages-und-dem-web-client-auf-ihrem-sgtm-hinzu\" class=\"wp-block-heading\">3. F\u00fcgen Sie das erweiterte Tracking-Skript zu den Leadpages und dem Web-Client auf Ihrem sGTM hinzu.<\/h3>\n\n\n\n<p>Anstelle des 'normalen' Web-GTM-Skripts setzen wir hier das <a href=\"https:\/\/taggrs.io\/docs\/server-side-tracking\/enhanced-tracking-script\">erweiterte TAGGRS-Tracking-Skript<\/a> ein. Dieses Skript sorgt daf\u00fcr, dass der Web-GTM-Container von unserem Server-GTM geladen wird. Dadurch wird sichergestellt, dass wir 1 bis 2% mehr messen k\u00f6nnen. Alle Cookie-Banner, die vollst\u00e4ndige GTM-Skripte blockieren, haben nun keine Auswirkungen mehr.<\/p>\n\n\n\n<p>Gehen Sie nun zu Ihrem Web-GTM-Container und kopieren Sie Ihre Web-GTM-Container-ID<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/copy-container-id-1024x741.png\" alt=\"go-web-gtm-container-kopieren-ihre-web-gtm container-id\" class=\"wp-image-53469\" title=\"\"><\/figure>\n\n\n\n<p>Gehen Sie in Ihrem TAGGRS-Container auf 'Erste Schritte'.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/go-get-started-1024x741.png\" alt=\"go-in-taggrs-container--to-get-started\" class=\"wp-image-53474\" title=\"\"><\/figure>\n\n\n\n<p>Scrollen Sie nach unten und klicken Sie auf Optimieren<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/scroll-click-optimize-1024x741.png\" alt=\"scroll-down-klick-optimieren.png\" class=\"wp-image-53479\" title=\"\"><\/figure>\n\n\n\n<p>W\u00e4hlen Sie 'Erweitertes Tracking-Skript'.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/choose-enhanced-script-1024x741.png\" alt=\"w\u00e4hle-erweitertes-tracking-skript.png\" class=\"wp-image-53484\" title=\"\"><\/figure>\n\n\n\n<p>Geben Sie Ihre GTM-Webcontainer-ID ein<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/submit-webcontainer-id-1024x741.png\" alt=\"submit-gtm-webcontainer-id\" class=\"wp-image-53489\" title=\"\"><\/figure>\n\n\n\n<p>Scrollen Sie nach unten und kopieren Sie Ihren HEAD-Code. Unten finden Sie auch einen BODY-Code, den Sie ebenfalls ben\u00f6tigen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/copy-head-code-1024x741.png\" alt=\"Copy-Head-Code\" class=\"wp-image-53494\" title=\"\"><\/figure>\n\n\n\n<p>Gehen Sie zu Ihrer Leadpage-Landing Page und klicken Sie auf Bearbeiten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/go-leadpage-edit-1024x741.png\" alt=\"go-leadpage-landingpage-click-edit\" class=\"wp-image-53504\" title=\"\"><\/figure>\n\n\n\n<p>Gehen Sie zu Ihren Einstellungen und w\u00e4hlen Sie dann Analytics.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/click-analytics-1024x741.png\" alt=\"Klick-Analysen\" class=\"wp-image-53514\" title=\"\"><\/figure>\n\n\n\n<p>F\u00fcgen Sie den Head-Code f\u00fcr den Head Section Tracking Code ein.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/paste-head-code-1024x741.png\" alt=\"Einf\u00fcgen-Kopf-Abschnitt-Verfolgungscode\" class=\"wp-image-53519\" title=\"\"><\/figure>\n\n\n\n<p>Machen Sie dasselbe f\u00fcr das Skript BODY aus Ihrem TAGGRS-Container.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/same-for-body-1024x741.png\" alt=\"Gleiche-f\u00fcr-K\u00f6rper\" class=\"wp-image-53524\" title=\"\"><\/figure>\n\n\n\n<p>Gehen Sie zu Ihrem Server-GTM-Container und w\u00e4hlen Sie Clients.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/container-choose-client-1024x741.webp\" alt=\"go-server-gtm-container-choose-client\" class=\"wp-image-53529\" title=\"\"><\/figure>\n\n\n\n<p>F\u00fcgen Sie einen neuen Client hinzu.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"740\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/add-new-client-2-1024x740.png\" alt=\"add-new-client\n\" class=\"wp-image-53544\" title=\"\"><\/figure>\n\n\n\n<p>W\u00e4hlen Sie Webcontainer.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/choose-webcontainer-1024x741.png\" alt=\"choose-webcontainer\" class=\"wp-image-53549\" title=\"\"><\/figure>\n\n\n\n<p>F\u00fcgen Sie Ihre Web-GTM-Container-ID ein.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/paste-id-2-1024x741.png\" alt=\"paste-web-gtm-container-id\" class=\"wp-image-53559\" style=\"width:840px;height:auto\" title=\"\"><\/figure>\n\n\n\n<p>Normalerweise k\u00f6nnen Sie die Option Regionsspezifische Einstellungen aktivieren deaktivieren. Klicken Sie auf 'Speichern'. Als n\u00e4chstes schalten Sie den Container live. Dadurch wird sichergestellt, dass Ihr Web-GTM \u00fcber Ihren Server-GTM geladen wird.   <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/save-gtm-1024x741.png\" alt=\"speichern-gtm\" class=\"wp-image-53574\" title=\"\"><\/figure>\n\n\n\n<h3 id=\"erweitern-sie-ihr-google-tag-mit-der-server-url-in-ihrem-web-gtm-container\" class=\"wp-block-heading\">Erweitern Sie Ihr Google Tag mit der Server-URL in Ihrem Web-GTM-Container<\/h3>\n\n\n\n<p>Auf diese Weise werden wir Daten von unserem Web-GTM an unser Server-GTM senden. Die Datenerfassung erfolgt weiterhin \u00fcber das Web-GTM. \u00dcber das Google Tag k\u00f6nnen wir eine Server-URL an den Ort \u00fcbermitteln, an den wir die Daten senden m\u00f6chten. Diese Daten werden vom GA4-Client im Server-Container empfangen und als Ereignisdaten angezeigt, so dass sie f\u00fcr die weitere Verwendung lesbar\/verwendbar sind.   <\/p>\n\n\n\n<p>Klicken Sie auf 'Tags' in Ihrem Web-GTM-Container<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/click-tags-container-1024x741.png\" alt=\"click-tags-we-gtm-container\" class=\"wp-image-53579\" title=\"\"><\/figure>\n\n\n\n<p>Klicken Sie auf Ihr Google Tag<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/click-google-tag-1024x741.png\" alt=\"klick-google-tag\" class=\"wp-image-53584\" title=\"\"><\/figure>\n\n\n\n<p>F\u00fcgen Sie eine server_container_url mit Ihrer taggrs-Subdomain hinzu<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/add-url-subdomain-1024x741.png\" alt=\"add-server-container-url-to-taggrs-subdomain\" class=\"wp-image-53589\" title=\"\"><\/figure>\n\n\n\n<p>Nun werden alle anderen GA4-Ereignisse in Ihrem Web-Container dieses Ereignis an Ihren Server-Container senden, wie hier 'GA4 | click'.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/event-send-server-1024x741.png\" alt=\"alle-GA4-Ereignisse-web-container-dieses-Ereignis-auf-ihren-Server-\u00fcbertragen\" class=\"wp-image-53600\" title=\"\"><\/figure>\n\n\n\n<h3 id=\"testen-sie-ob-ereignisse-vom-web-gtm-an-sgtm-gesendet-werden\" class=\"wp-block-heading\">Testen Sie, ob Ereignisse vom Web-GTM an sGTM gesendet werden<\/h3>\n\n\n\n<p>Wechseln Sie in den Vorschaumodus Ihres Server-Containers. Lesen Sie unseren <a href=\"https:\/\/taggrs.io\/docs\/server-side-tracking\/setup\/test-configuration\">umfassenden Leitfaden zum Testen von Server Side Tracking<\/a>, wenn Sie weitere Informationen dazu w\u00fcnschen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/preview-mode-container-1024x741.png\" alt=\"preview-mode-server-container\" class=\"wp-image-53607\" title=\"\"><\/figure>\n\n\n\n<p>Gehen Sie gleichzeitig in den Vorschaumodus Ihres Webcontainers.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/preview-mode-web-1024x741.png\" alt=\"preview-mode-web-container\" class=\"wp-image-53614\" title=\"\"><\/figure>\n\n\n\n<p>Jetzt k\u00f6nnen Sie die Ereignisse sehen, die in Ihrem Server-Container eingehen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/events-in-container-1024x741.png\" alt=\"events-come-in-server-container\" class=\"wp-image-53628\" title=\"\"><\/figure>\n\n\n\n<h3 id=\"senden-von-daten-an-ga4-von-ihrem-server-gtm-container\" class=\"wp-block-heading\">Senden von Daten an GA4 von Ihrem Server-GTM-Container.<\/h3>\n\n\n\n<p>Jetzt, da der Container getestet wurde, werden wir die Daten vom Server-Container an GA4 senden. Gehen Sie zu Ihrem Server-GTM-Container und klicken Sie auf 'Tags'. <\/p>\n\n\n\n<p>Erstellen Sie ein neues GA4-Tag und geben Sie die Messungs-ID ein. Feuern Sie dieses Tag, wenn 'client = GA4'. Denn wir m\u00f6chten alle Daten, die wir von unserem Web-GTM-Container erhalten, an GA4 weiterleiten. Da diese Web-GTM-Daten vom GA4-Client empfangen werden, k\u00f6nnen wir sagen, dass wir dieses sGTM-GA4-Tag jedes Mal ausl\u00f6sen wollen, wenn der Client = GA4 ist.   <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"741\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/fill-in-id-1024x741.png\" alt=\"new-ga4-tag-and-fill-in-measurement-id\" class=\"wp-image-53638\" title=\"\"><\/figure>\n\n\n\n<p>Jetzt werden also alle Daten, die \u00fcber GA4-Tags kommen, vom Web-GTM an den Server-GTM und damit an GA4 gesendet.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"730\" src=\"https:\/\/taggrs.io\/wp-content\/uploads\/2024\/10\/data-send-1024x730.png\" alt=\"all-data-via-ga4-tags-send-from-web-gtm-to-server-gtm-to-ga4\" class=\"wp-image-53643\" title=\"\"><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"outro\">Outro<\/h2>\n\n\n\n<p>Sie sind nun in der Lage, Server Side Tracking f\u00fcr Ihre Leadpages Landing Pages einzurichten. Dies liefert Ihnen genauere Daten, die nicht durch Einschr\u00e4nkungen wie Cookie-Banner behindert werden, und hilft Ihnen, wertvolle Erkenntnisse zu gewinnen.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie m\u00f6chten serverseitige Benutzerdaten von Ihrer Leadpages-Landing Page messen. In diesem Blog f\u00fchren wir Sie ...<\/p>\n","protected":false},"author":10,"featured_media":53664,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[348],"tags":[],"class_list":["post-53670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-server-side-tracking-de-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/taggrs.io\/de\/wp-json\/wp\/v2\/posts\/53670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taggrs.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taggrs.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taggrs.io\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/taggrs.io\/de\/wp-json\/wp\/v2\/comments?post=53670"}],"version-history":[{"count":2,"href":"https:\/\/taggrs.io\/de\/wp-json\/wp\/v2\/posts\/53670\/revisions"}],"predecessor-version":[{"id":65617,"href":"https:\/\/taggrs.io\/de\/wp-json\/wp\/v2\/posts\/53670\/revisions\/65617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taggrs.io\/de\/wp-json\/wp\/v2\/media\/53664"}],"wp:attachment":[{"href":"https:\/\/taggrs.io\/de\/wp-json\/wp\/v2\/media?parent=53670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taggrs.io\/de\/wp-json\/wp\/v2\/categories?post=53670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taggrs.io\/de\/wp-json\/wp\/v2\/tags?post=53670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}